{"id":6673,"date":"2014-09-29T00:00:26","date_gmt":"2014-09-29T03:00:26","guid":{"rendered":"https:\/\/ilc.desarrollos.want.cl\/cambio-en-el-directorio-de-ilc-en\/"},"modified":"2014-09-29T00:00:26","modified_gmt":"2014-09-29T03:00:26","slug":"cambio-en-el-directorio-de-ilc-en","status":"publish","type":"post","link":"https:\/\/ilcinversiones.cl\/en\/cambio-en-el-directorio-de-ilc-en\/","title":{"rendered":"Cambio en el Directorio de ILC"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[46],"class_list":["post-6673","post","type-post","status-publish","format-standard","hentry","category-essential-facts"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cambio en el Directorio de ILC - ILC Inversiones<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ilcinversiones.cl\/en\/cambio-en-el-directorio-de-ilc-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cambio en el Directorio de ILC - ILC Inversiones\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ilcinversiones.cl\/en\/cambio-en-el-directorio-de-ilc-en\/\" \/>\n<meta property=\"og:site_name\" content=\"ILC Inversiones\" \/>\n<meta property=\"article:published_time\" content=\"2014-09-29T03:00:26+00:00\" \/>\n<meta name=\"author\" content=\"soporte.want\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"soporte.want\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cambio en el Directorio de ILC - ILC Inversiones","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ilcinversiones.cl\/en\/cambio-en-el-directorio-de-ilc-en\/","og_locale":"en_US","og_type":"article","og_title":"Cambio en el Directorio de ILC - ILC Inversiones","og_url":"https:\/\/ilcinversiones.cl\/en\/cambio-en-el-directorio-de-ilc-en\/","og_site_name":"ILC Inversiones","article_published_time":"2014-09-29T03:00:26+00:00","author":"soporte.want","twitter_card":"summary_large_image","twitter_misc":{"Written by":"soporte.want"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ilcinversiones.cl\/en\/cambio-en-el-directorio-de-ilc-en\/#article","isPartOf":{"@id":"https:\/\/ilcinversiones.cl\/en\/cambio-en-el-directorio-de-ilc-en\/"},"author":{"name":"soporte.want","@id":"https:\/\/ilcinversiones.cl\/en\/#\/schema\/person\/8eb7c2ee6f41c81944ef9a4ade830634"},"headline":"Cambio en el Directorio de ILC","datePublished":"2014-09-29T03:00:26+00:00","mainEntityOfPage":{"@id":"https:\/\/ilcinversiones.cl\/en\/cambio-en-el-directorio-de-ilc-en\/"},"wordCount":6,"publisher":{"@id":"https:\/\/ilcinversiones.cl\/en\/#organization"},"articleSection":["Material Facts"],"inLanguage":"en-US"},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/ilcinversiones.cl\/en\/cambio-en-el-directorio-de-ilc-en\/","url":"https:\/\/ilcinversiones.cl\/en\/cambio-en-el-directorio-de-ilc-en\/","name":"Cambio en el Directorio de ILC - ILC Inversiones","isPartOf":{"@id":"https:\/\/ilcinversiones.cl\/en\/#website"},"datePublished":"2014-09-29T03:00:26+00:00","breadcrumb":{"@id":"https:\/\/ilcinversiones.cl\/en\/cambio-en-el-directorio-de-ilc-en\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ilcinversiones.cl\/en\/cambio-en-el-directorio-de-ilc-en\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ilcinversiones.cl\/en\/cambio-en-el-directorio-de-ilc-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ilcinversiones.cl\/en\/"},{"@type":"ListItem","position":2,"name":"Cambio en el Directorio de ILC"}]},{"@type":"WebSite","@id":"https:\/\/ilcinversiones.cl\/en\/#website","url":"https:\/\/ilcinversiones.cl\/en\/","name":"ILC Inversiones","description":"La construcci\u00f3n","publisher":{"@id":"https:\/\/ilcinversiones.cl\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ilcinversiones.cl\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/ilcinversiones.cl\/en\/#organization","name":"ILC Inversiones","url":"https:\/\/ilcinversiones.cl\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ilcinversiones.cl\/en\/#\/schema\/logo\/image\/","url":"https:\/\/ilcinversiones.cl\/app\/uploads\/2025\/03\/LOGO-45-anos_ok_color-1-2.png","contentUrl":"https:\/\/ilcinversiones.cl\/app\/uploads\/2025\/03\/LOGO-45-anos_ok_color-1-2.png","width":1630,"height":740,"caption":"ILC Inversiones"},"image":{"@id":"https:\/\/ilcinversiones.cl\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/ilc-inversiones-la-construcci-n\/posts\/?feedView=all"]},{"@type":"Person","@id":"https:\/\/ilcinversiones.cl\/en\/#\/schema\/person\/8eb7c2ee6f41c81944ef9a4ade830634","name":"soporte.want","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/0db21c0b96af5ce5bbd458596beca70750291cfe5e426e36e925d74065720623?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0db21c0b96af5ce5bbd458596beca70750291cfe5e426e36e925d74065720623?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0db21c0b96af5ce5bbd458596beca70750291cfe5e426e36e925d74065720623?s=96&d=mm&r=g","caption":"soporte.want"},"sameAs":["https:\/\/ilc-inversiones.test\/wp"]}]}},"_links":{"self":[{"href":"https:\/\/ilcinversiones.cl\/en\/wp-json\/wp\/v2\/posts\/6673","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ilcinversiones.cl\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ilcinversiones.cl\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ilcinversiones.cl\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ilcinversiones.cl\/en\/wp-json\/wp\/v2\/comments?post=6673"}],"version-history":[{"count":0,"href":"https:\/\/ilcinversiones.cl\/en\/wp-json\/wp\/v2\/posts\/6673\/revisions"}],"wp:attachment":[{"href":"https:\/\/ilcinversiones.cl\/en\/wp-json\/wp\/v2\/media?parent=6673"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ilcinversiones.cl\/en\/wp-json\/wp\/v2\/categories?post=6673"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}