{"id":6608,"date":"2017-11-03T14:10:34","date_gmt":"2017-11-03T17:10:34","guid":{"rendered":"https:\/\/ilc.desarrollos.want.cl\/vida-camara-publica-resultados-financieros-9m17-en\/"},"modified":"2025-04-08T00:46:32","modified_gmt":"2025-04-08T04:46:32","slug":"vida-camara-publica-resultados-financieros-9m17-en","status":"publish","type":"post","link":"https:\/\/ilcinversiones.cl\/en\/vida-camara-publica-resultados-financieros-9m17-en\/","title":{"rendered":"Vida C\u00e1mara publica resultados financieros 9M17"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":2363,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1],"class_list":["post-6608","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-press-releases"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vida C\u00e1mara publica resultados financieros 9M17 - ILC Inversiones<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ilcinversiones.cl\/en\/vida-camara-publica-resultados-financieros-9m17-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vida C\u00e1mara publica resultados financieros 9M17 - ILC Inversiones\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ilcinversiones.cl\/en\/vida-camara-publica-resultados-financieros-9m17-en\/\" \/>\n<meta property=\"og:site_name\" content=\"ILC Inversiones\" \/>\n<meta property=\"article:published_time\" content=\"2017-11-03T17:10:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-08T04:46:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ilcinversiones.cl\/app\/uploads\/2025\/01\/Vida-Camara-3-1-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1335\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"soporte.want\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"soporte.want\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vida C\u00e1mara publica resultados financieros 9M17 - ILC Inversiones","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ilcinversiones.cl\/en\/vida-camara-publica-resultados-financieros-9m17-en\/","og_locale":"en_US","og_type":"article","og_title":"Vida C\u00e1mara publica resultados financieros 9M17 - ILC Inversiones","og_url":"https:\/\/ilcinversiones.cl\/en\/vida-camara-publica-resultados-financieros-9m17-en\/","og_site_name":"ILC Inversiones","article_published_time":"2017-11-03T17:10:34+00:00","article_modified_time":"2025-04-08T04:46:32+00:00","og_image":[{"width":2000,"height":1335,"url":"https:\/\/ilcinversiones.cl\/app\/uploads\/2025\/01\/Vida-Camara-3-1-1.jpg","type":"image\/jpeg"}],"author":"soporte.want","twitter_card":"summary_large_image","twitter_misc":{"Written by":"soporte.want"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ilcinversiones.cl\/en\/vida-camara-publica-resultados-financieros-9m17-en\/#article","isPartOf":{"@id":"https:\/\/ilcinversiones.cl\/en\/vida-camara-publica-resultados-financieros-9m17-en\/"},"author":{"name":"soporte.want","@id":"https:\/\/ilcinversiones.cl\/en\/#\/schema\/person\/8eb7c2ee6f41c81944ef9a4ade830634"},"headline":"Vida C\u00e1mara publica resultados financieros 9M17","datePublished":"2017-11-03T17:10:34+00:00","dateModified":"2025-04-08T04:46:32+00:00","mainEntityOfPage":{"@id":"https:\/\/ilcinversiones.cl\/en\/vida-camara-publica-resultados-financieros-9m17-en\/"},"wordCount":7,"publisher":{"@id":"https:\/\/ilcinversiones.cl\/en\/#organization"},"image":{"@id":"https:\/\/ilcinversiones.cl\/en\/vida-camara-publica-resultados-financieros-9m17-en\/#primaryimage"},"thumbnailUrl":"https:\/\/ilcinversiones.cl\/app\/uploads\/2025\/01\/Vida-Camara-3-1-1.jpg","articleSection":["Press Releases"],"inLanguage":"en-US"},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/ilcinversiones.cl\/en\/vida-camara-publica-resultados-financieros-9m17-en\/","url":"https:\/\/ilcinversiones.cl\/en\/vida-camara-publica-resultados-financieros-9m17-en\/","name":"Vida C\u00e1mara publica resultados financieros 9M17 - ILC Inversiones","isPartOf":{"@id":"https:\/\/ilcinversiones.cl\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ilcinversiones.cl\/en\/vida-camara-publica-resultados-financieros-9m17-en\/#primaryimage"},"image":{"@id":"https:\/\/ilcinversiones.cl\/en\/vida-camara-publica-resultados-financieros-9m17-en\/#primaryimage"},"thumbnailUrl":"https:\/\/ilcinversiones.cl\/app\/uploads\/2025\/01\/Vida-Camara-3-1-1.jpg","datePublished":"2017-11-03T17:10:34+00:00","dateModified":"2025-04-08T04:46:32+00:00","breadcrumb":{"@id":"https:\/\/ilcinversiones.cl\/en\/vida-camara-publica-resultados-financieros-9m17-en\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ilcinversiones.cl\/en\/vida-camara-publica-resultados-financieros-9m17-en\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ilcinversiones.cl\/en\/vida-camara-publica-resultados-financieros-9m17-en\/#primaryimage","url":"https:\/\/ilcinversiones.cl\/app\/uploads\/2025\/01\/Vida-Camara-3-1-1.jpg","contentUrl":"https:\/\/ilcinversiones.cl\/app\/uploads\/2025\/01\/Vida-Camara-3-1-1.jpg","width":2000,"height":1335},{"@type":"BreadcrumbList","@id":"https:\/\/ilcinversiones.cl\/en\/vida-camara-publica-resultados-financieros-9m17-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ilcinversiones.cl\/en\/"},{"@type":"ListItem","position":2,"name":"Vida C\u00e1mara publica resultados financieros 9M17"}]},{"@type":"WebSite","@id":"https:\/\/ilcinversiones.cl\/en\/#website","url":"https:\/\/ilcinversiones.cl\/en\/","name":"ILC Inversiones","description":"La construcci\u00f3n","publisher":{"@id":"https:\/\/ilcinversiones.cl\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ilcinversiones.cl\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/ilcinversiones.cl\/en\/#organization","name":"ILC Inversiones","url":"https:\/\/ilcinversiones.cl\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ilcinversiones.cl\/en\/#\/schema\/logo\/image\/","url":"https:\/\/ilcinversiones.cl\/app\/uploads\/2025\/03\/LOGO-45-anos_ok_color-1-2.png","contentUrl":"https:\/\/ilcinversiones.cl\/app\/uploads\/2025\/03\/LOGO-45-anos_ok_color-1-2.png","width":1630,"height":740,"caption":"ILC Inversiones"},"image":{"@id":"https:\/\/ilcinversiones.cl\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/ilc-inversiones-la-construcci-n\/posts\/?feedView=all"]},{"@type":"Person","@id":"https:\/\/ilcinversiones.cl\/en\/#\/schema\/person\/8eb7c2ee6f41c81944ef9a4ade830634","name":"soporte.want","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/0db21c0b96af5ce5bbd458596beca70750291cfe5e426e36e925d74065720623?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0db21c0b96af5ce5bbd458596beca70750291cfe5e426e36e925d74065720623?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0db21c0b96af5ce5bbd458596beca70750291cfe5e426e36e925d74065720623?s=96&d=mm&r=g","caption":"soporte.want"},"sameAs":["https:\/\/ilc-inversiones.test\/wp"]}]}},"_links":{"self":[{"href":"https:\/\/ilcinversiones.cl\/en\/wp-json\/wp\/v2\/posts\/6608","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ilcinversiones.cl\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ilcinversiones.cl\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ilcinversiones.cl\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ilcinversiones.cl\/en\/wp-json\/wp\/v2\/comments?post=6608"}],"version-history":[{"count":1,"href":"https:\/\/ilcinversiones.cl\/en\/wp-json\/wp\/v2\/posts\/6608\/revisions"}],"predecessor-version":[{"id":6834,"href":"https:\/\/ilcinversiones.cl\/en\/wp-json\/wp\/v2\/posts\/6608\/revisions\/6834"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ilcinversiones.cl\/en\/wp-json\/wp\/v2\/media\/2363"}],"wp:attachment":[{"href":"https:\/\/ilcinversiones.cl\/en\/wp-json\/wp\/v2\/media?parent=6608"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ilcinversiones.cl\/en\/wp-json\/wp\/v2\/categories?post=6608"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}